{"id":264,"count":0,"description":"","link":"https:\/\/alimentsalento.com\/es\/categoria-producto\/vino-y-licores\/vino-rosado\/","name":"Vino Rosado","slug":"vino-rosado","taxonomy":"product_cat","parent":258,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vino Rosado Archivi - Aliments Salento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alimentsalento.com\/es\/categoria-producto\/vino-y-licores\/vino-rosado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vino Rosado Archivi - Aliments Salento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alimentsalento.com\/es\/categoria-producto\/vino-y-licores\/vino-rosado\/\" \/>\n<meta property=\"og:site_name\" content=\"Aliments Salento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/categoria-producto\\\/vino-y-licores\\\/vino-rosado\\\/\",\"url\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/categoria-producto\\\/vino-y-licores\\\/vino-rosado\\\/\",\"name\":\"Vino Rosado Archivi - Aliments Salento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/categoria-producto\\\/vino-y-licores\\\/vino-rosado\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/categoria-producto\\\/vino-y-licores\\\/vino-rosado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vino y Licores\",\"item\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/categoria-producto\\\/vino-y-licores\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vino Rosado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/\",\"name\":\"Aliments Salento\",\"description\":\"Benvenuti in Salento, terra di sapori e di colori.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/#organization\",\"name\":\"Aliments Salento\",\"url\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alimentsalento.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/AlimentsalentoSLchef6.png\",\"contentUrl\":\"https:\\\/\\\/alimentsalento.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/AlimentsalentoSLchef6.png\",\"width\":542,\"height\":176,\"caption\":\"Aliments Salento\"},\"image\":{\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/alimentssalento\",\"https:\\\/\\\/www.instagram.com\\\/aliments_salento\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aliments-salento\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vino Rosado Archivi - Aliments Salento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alimentsalento.com\/es\/categoria-producto\/vino-y-licores\/vino-rosado\/","og_locale":"es_ES","og_type":"article","og_title":"Vino Rosado Archivi - Aliments Salento","og_url":"https:\/\/alimentsalento.com\/es\/categoria-producto\/vino-y-licores\/vino-rosado\/","og_site_name":"Aliments Salento","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/alimentsalento.com\/es\/categoria-producto\/vino-y-licores\/vino-rosado\/","url":"https:\/\/alimentsalento.com\/es\/categoria-producto\/vino-y-licores\/vino-rosado\/","name":"Vino Rosado Archivi - Aliments Salento","isPartOf":{"@id":"https:\/\/alimentsalento.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/alimentsalento.com\/es\/categoria-producto\/vino-y-licores\/vino-rosado\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/alimentsalento.com\/es\/categoria-producto\/vino-y-licores\/vino-rosado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alimentsalento.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vino y Licores","item":"https:\/\/alimentsalento.com\/es\/categoria-producto\/vino-y-licores\/"},{"@type":"ListItem","position":3,"name":"Vino Rosado"}]},{"@type":"WebSite","@id":"https:\/\/alimentsalento.com\/es\/#website","url":"https:\/\/alimentsalento.com\/es\/","name":"Aliments Salento","description":"Benvenuti in Salento, terra di sapori e di colori.","publisher":{"@id":"https:\/\/alimentsalento.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alimentsalento.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/alimentsalento.com\/es\/#organization","name":"Aliments Salento","url":"https:\/\/alimentsalento.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alimentsalento.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/alimentsalento.com\/wp-content\/uploads\/2021\/12\/AlimentsalentoSLchef6.png","contentUrl":"https:\/\/alimentsalento.com\/wp-content\/uploads\/2021\/12\/AlimentsalentoSLchef6.png","width":542,"height":176,"caption":"Aliments Salento"},"image":{"@id":"https:\/\/alimentsalento.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alimentssalento","https:\/\/www.instagram.com\/aliments_salento\/","https:\/\/www.linkedin.com\/company\/aliments-salento"]}]}},"_links":{"self":[{"href":"https:\/\/alimentsalento.com\/es\/wp-json\/wp\/v2\/product_cat\/264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alimentsalento.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/alimentsalento.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/alimentsalento.com\/es\/wp-json\/wp\/v2\/product_cat\/258"}],"wp:post_type":[{"href":"https:\/\/alimentsalento.com\/es\/wp-json\/wp\/v2\/product?product_cat=264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}