{"id":169,"count":0,"description":"","link":"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/body-line\/body\/","name":"Body","slug":"body","taxonomy":"product_cat","parent":166,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Body Archivi - Aliments Salento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/body-line\/body\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Body Archivi - Aliments Salento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/body-line\/body\/\" \/>\n<meta property=\"og:site_name\" content=\"Aliments Salento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/product-category\\\/cosmetics\\\/body-line\\\/body\\\/\",\"url\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/product-category\\\/cosmetics\\\/body-line\\\/body\\\/\",\"name\":\"Body Archivi - Aliments Salento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/product-category\\\/cosmetics\\\/body-line\\\/body\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/product-category\\\/cosmetics\\\/body-line\\\/body\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosmetics\",\"item\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/product-category\\\/cosmetics\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Body Line\",\"item\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/product-category\\\/cosmetics\\\/body-line\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Body\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/\",\"name\":\"Aliments Salento\",\"description\":\"Benvenuti in Salento, terra di sapori e di colori.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/#organization\",\"name\":\"Aliments Salento\",\"url\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alimentsalento.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/AlimentsalentoSLchef6.png\",\"contentUrl\":\"https:\\\/\\\/alimentsalento.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/AlimentsalentoSLchef6.png\",\"width\":542,\"height\":176,\"caption\":\"Aliments Salento\"},\"image\":{\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/alimentssalento\",\"https:\\\/\\\/www.instagram.com\\\/aliments_salento\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aliments-salento\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Body Archivi - Aliments Salento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/body-line\/body\/","og_locale":"en_US","og_type":"article","og_title":"Body Archivi - Aliments Salento","og_url":"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/body-line\/body\/","og_site_name":"Aliments Salento","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/body-line\/body\/","url":"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/body-line\/body\/","name":"Body Archivi - Aliments Salento","isPartOf":{"@id":"https:\/\/alimentsalento.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/body-line\/body\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/body-line\/body\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alimentsalento.com\/en\/"},{"@type":"ListItem","position":2,"name":"Cosmetics","item":"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/"},{"@type":"ListItem","position":3,"name":"Body Line","item":"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/body-line\/"},{"@type":"ListItem","position":4,"name":"Body"}]},{"@type":"WebSite","@id":"https:\/\/alimentsalento.com\/en\/#website","url":"https:\/\/alimentsalento.com\/en\/","name":"Aliments Salento","description":"Benvenuti in Salento, terra di sapori e di colori.","publisher":{"@id":"https:\/\/alimentsalento.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alimentsalento.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alimentsalento.com\/en\/#organization","name":"Aliments Salento","url":"https:\/\/alimentsalento.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alimentsalento.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/alimentsalento.com\/wp-content\/uploads\/2021\/12\/AlimentsalentoSLchef6.png","contentUrl":"https:\/\/alimentsalento.com\/wp-content\/uploads\/2021\/12\/AlimentsalentoSLchef6.png","width":542,"height":176,"caption":"Aliments Salento"},"image":{"@id":"https:\/\/alimentsalento.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alimentssalento","https:\/\/www.instagram.com\/aliments_salento\/","https:\/\/www.linkedin.com\/company\/aliments-salento"]}]}},"_links":{"self":[{"href":"https:\/\/alimentsalento.com\/en\/wp-json\/wp\/v2\/product_cat\/169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alimentsalento.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/alimentsalento.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/alimentsalento.com\/en\/wp-json\/wp\/v2\/product_cat\/166"}],"wp:post_type":[{"href":"https:\/\/alimentsalento.com\/en\/wp-json\/wp\/v2\/product?product_cat=169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}