{"id":6719,"date":"2022-01-14T09:02:43","date_gmt":"2022-01-14T08:02:43","guid":{"rendered":"https:\/\/alimentsalento.com\/cosmetics\/"},"modified":"2022-01-20T12:15:44","modified_gmt":"2022-01-20T11:15:44","slug":"cosmetics","status":"publish","type":"page","link":"https:\/\/alimentsalento.com\/en\/cosmetics\/","title":{"rendered":"Cosmetics"},"content":{"rendered":"<p>[vc_row css_animation=&#8221;fadeIn&#8221; type=&#8221;boxed&#8221; css=&#8221;.vc_custom_1487082335567{margin-bottom: 75px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1638377567437{margin-top: 100px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1638441954242{margin-bottom: 75px !important;}&#8221;]<\/p>\n<h1 style=\"text-align: center;\">Cosmetics<\/h1>\n<p style=\"text-align: center;\">A selection of the best cosmetic products of Salento<\/p>\n<p>[\/vc_column_text]<div class=\"row\"><div class=\"categories_grid\">\n\t\t\t<div class=\"category_two_cat_1\">\n\t\t\t\t<div class=\"category_grid_box\">\n\t\t\t\t\t<span class=\"category_item_bkg\" style=\"background-image:url(https:\/\/alimentsalento.com\/wp-content\/uploads\/2021\/12\/linea-corpo.webp)\"><\/span>\n\t\t\t\t\t<a href=\"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/body-line\/\" class=\"category_item\" >\n\t\t\t\t\t\t<span class=\"category_name\">Body Line\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t<div class=\"category_two_cat_2\">\n\t\t\t\t<div class=\"category_grid_box\">\n\t\t\t\t\t<span class=\"category_item_bkg\" style=\"background-image:url(https:\/\/alimentsalento.com\/wp-content\/uploads\/2021\/12\/linea-viso.jpg)\"><\/span>\n\t\t\t\t\t<a href=\"https:\/\/alimentsalento.com\/en\/product-category\/cosmetics\/face-line\/\" class=\"category_item\" >\n\t\t\t\t\t\t<span class=\"category_name\">Face Line\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t<div class=\"clearfix\"><\/div>\n\n\t\t<\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=&#8221;fadeIn&#8221; type=&#8221;boxed&#8221; css=&#8221;.vc_custom_1487082335567{margin-bottom: 75px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1638377567437{margin-top: 100px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1638441954242{margin-bottom: 75px !important;}&#8221;] Cosmetics A selection of the best cosmetic products of Salento [\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6719","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cosmetics - Aliments Salento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alimentsalento.com\/en\/cosmetics\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cosmetics - Aliments Salento\" \/>\n<meta property=\"og:description\" content=\"[vc_row css_animation=&#8221;fadeIn&#8221; type=&#8221;boxed&#8221; css=&#8221;.vc_custom_1487082335567{margin-bottom: 75px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1638377567437{margin-top: 100px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1638441954242{margin-bottom: 75px !important;}&#8221;] Cosmetics A selection of the best cosmetic products of Salento [\/vc_column_text][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alimentsalento.com\/en\/cosmetics\/\" \/>\n<meta property=\"og:site_name\" content=\"Aliments Salento\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/alimentssalento\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-20T11:15:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/cosmetics\\\/\",\"url\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/cosmetics\\\/\",\"name\":\"Cosmetics - Aliments Salento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/#website\"},\"datePublished\":\"2022-01-14T08:02:43+00:00\",\"dateModified\":\"2022-01-20T11:15:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/cosmetics\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alimentsalento.com\\\/en\\\/cosmetics\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/cosmetics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosmetics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/\",\"name\":\"Aliments Salento\",\"description\":\"Benvenuti in Salento, terra di sapori e di colori.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/#organization\",\"name\":\"Aliments Salento\",\"url\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alimentsalento.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/AlimentsalentoSLchef6.png\",\"contentUrl\":\"https:\\\/\\\/alimentsalento.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/AlimentsalentoSLchef6.png\",\"width\":542,\"height\":176,\"caption\":\"Aliments Salento\"},\"image\":{\"@id\":\"https:\\\/\\\/alimentsalento.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/alimentssalento\",\"https:\\\/\\\/www.instagram.com\\\/aliments_salento\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aliments-salento\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cosmetics - Aliments Salento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alimentsalento.com\/en\/cosmetics\/","og_locale":"en_US","og_type":"article","og_title":"Cosmetics - Aliments Salento","og_description":"[vc_row css_animation=&#8221;fadeIn&#8221; type=&#8221;boxed&#8221; css=&#8221;.vc_custom_1487082335567{margin-bottom: 75px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1638377567437{margin-top: 100px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1638441954242{margin-bottom: 75px !important;}&#8221;] Cosmetics A selection of the best cosmetic products of Salento [\/vc_column_text][\/vc_column][\/vc_row]","og_url":"https:\/\/alimentsalento.com\/en\/cosmetics\/","og_site_name":"Aliments Salento","article_publisher":"https:\/\/www.facebook.com\/alimentssalento","article_modified_time":"2022-01-20T11:15:44+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alimentsalento.com\/en\/cosmetics\/","url":"https:\/\/alimentsalento.com\/en\/cosmetics\/","name":"Cosmetics - Aliments Salento","isPartOf":{"@id":"https:\/\/alimentsalento.com\/en\/#website"},"datePublished":"2022-01-14T08:02:43+00:00","dateModified":"2022-01-20T11:15:44+00:00","breadcrumb":{"@id":"https:\/\/alimentsalento.com\/en\/cosmetics\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alimentsalento.com\/en\/cosmetics\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alimentsalento.com\/en\/cosmetics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alimentsalento.com\/en\/"},{"@type":"ListItem","position":2,"name":"Cosmetics"}]},{"@type":"WebSite","@id":"https:\/\/alimentsalento.com\/en\/#website","url":"https:\/\/alimentsalento.com\/en\/","name":"Aliments Salento","description":"Benvenuti in Salento, terra di sapori e di colori.","publisher":{"@id":"https:\/\/alimentsalento.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alimentsalento.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alimentsalento.com\/en\/#organization","name":"Aliments Salento","url":"https:\/\/alimentsalento.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alimentsalento.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/alimentsalento.com\/wp-content\/uploads\/2021\/12\/AlimentsalentoSLchef6.png","contentUrl":"https:\/\/alimentsalento.com\/wp-content\/uploads\/2021\/12\/AlimentsalentoSLchef6.png","width":542,"height":176,"caption":"Aliments Salento"},"image":{"@id":"https:\/\/alimentsalento.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alimentssalento","https:\/\/www.instagram.com\/aliments_salento\/","https:\/\/www.linkedin.com\/company\/aliments-salento"]}]}},"_links":{"self":[{"href":"https:\/\/alimentsalento.com\/en\/wp-json\/wp\/v2\/pages\/6719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alimentsalento.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alimentsalento.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alimentsalento.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alimentsalento.com\/en\/wp-json\/wp\/v2\/comments?post=6719"}],"version-history":[{"count":0,"href":"https:\/\/alimentsalento.com\/en\/wp-json\/wp\/v2\/pages\/6719\/revisions"}],"wp:attachment":[{"href":"https:\/\/alimentsalento.com\/en\/wp-json\/wp\/v2\/media?parent=6719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}